﻿{"id":30761,"date":"2021-10-04T10:50:46","date_gmt":"2021-10-04T10:50:46","guid":{"rendered":"https:\/\/sercalia.com\/sistemas-de-enchimento-de-bolhas-em-caixas\/"},"modified":"2024-08-07T14:29:26","modified_gmt":"2024-08-07T14:29:26","slug":"sistemas-de-relleno-con-burbujas-en-cajas","status":"publish","type":"page","link":"https:\/\/sercalia.com\/pt\/sistemas-de-relleno-con-burbujas-en-cajas\/","title":{"rendered":"Enchimento para caixas"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.24.0&#8243; background_color=&#8221;RGBA(255,255,255,0)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_fullwidth_header title=&#8221;SISTEMAS DE ENCHIMENTO DE BOLHAS EM CAIXAS&#8221; admin_label=&#8221;Fullwidth Header&#8221; _builder_version=&#8221;4.24.0&#8243; title_text_color=&#8221;#366393&#8243; title_font_size=&#8221;33px&#8221; content_font=&#8221;|600|||||||&#8221; content_text_color=&#8221;#0C71C3&#8243; subhead_font_size=&#8221;19px&#8221; background_enable_color=&#8221;off&#8221; background_image=&#8221;https:\/\/sercalia.com\/wp-content\/uploads\/2023\/10\/proteccion-sercalia.webp&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;center_left&#8221; max_width=&#8221;1330px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;60px||20px|80px|false|false&#8221; custom_padding_tablet=&#8221;10px||0px|80px|false|false&#8221; custom_padding_phone=&#8221;0px||0px|0px|false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; animation_style=&#8221;zoom&#8221; animation_direction=&#8221;left&#8221; animation_intensity_zoom=&#8221;4%&#8221; background_last_edited=&#8221;on|desktop&#8221; background_size_phone=&#8221;custom&#8221; background_image_width_phone=&#8221;35%&#8221; background_position_phone=&#8221;center_right&#8221; background_horizontal_offset_phone=&#8221;0%&#8221; background_vertical_offset_phone=&#8221;4%&#8221; global_colors_info=&#8221;{}&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<a href=\"https:\/\/sercalia.com\/pt\/acondicionamento\/\">Produtos de Acondicionamento<\/a> | Prote\u00e7\u00e3o[\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; specialty=&#8221;on&#8221; padding_top_1=&#8221;0px&#8221; padding_top_bottom_link_1=&#8221;false&#8221; padding_left_right_link_1=&#8221;false&#8221; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;RGBA(255,255,255,0)&#8221; inner_max_width=&#8221;1330px&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_sidebar area=&#8221;sidebar-1&#8243; disabled_on=&#8221;on|on|off&#8221; admin_label=&#8221;Sidebar&#8221; _builder_version=&#8221;4.16&#8243; remove_border=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_sidebar][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; specialty_columns=&#8221;3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_row_inner _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;0px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.24.0&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_margin_tablet=&#8221;0px||||false|false&#8221; custom_margin_phone=&#8221;-80px||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>M\u00e1quinas e bobinas de sacos de ar insufl\u00e1veis e bolhas AIRmove para prote\u00e7\u00e3o e envio de pequenas quantidades de embalagens.<\/h2>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.24.0&#8243; custom_padding=&#8221;0px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/sercalia.com\/wp-content\/uploads\/2021\/07\/sercalia_airmove.jpg&#8221; alt=&#8221;AIRmove. Sistema de enchimento de embalagem. Sercalia&#8221; title_text=&#8221;AIRmove. Sistema de enchimento de embalagem. Sercalia&#8221; url=&#8221;https:\/\/conservatis.com\/es\/aplicaciones\/maquina-airmove&#8221; url_new_window=&#8221;on&#8221; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.17.6&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;500ms&#8221; animation_intensity_slide=&#8221;10%&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; animation=&#8221;left&#8221; sticky=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.17.6&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Descri\u00e7\u00e3o<\/h3>\n<p>Os sistemas de enchimento de bolhas AIRmove em caixas s\u00e3o a solu\u00e7\u00e3o perfeita para a prote\u00e7\u00e3o com airbags ou sacos insufl\u00e1veis para envios pequenos e m\u00e9dios (30 a 500 envios di\u00e1rios).<\/p>\n<p>Dispomos de 2 sistemas de enchimento, Airmove e Airmove2, e respetivas bobinas.<\/p>\n<p>A <strong>AIRmove<\/strong> \u00e9 a m\u00e1quina de enchimento de sacos de ar <strong>mais econ\u00f3mica<\/strong>. Recomendada <strong>at\u00e9 30 envios di\u00e1rios. <\/strong>Protege os seus produtos contra vibra\u00e7\u00f5es e choques. Permite preencher espa\u00e7os vazios, embrulhar e fixar produtos nas suas embalagens. Assim, assegura que os seus envios cheguem em perfeitas condi\u00e7\u00f5es.<\/p>\n<p>O seu sistema permite a <strong>produ\u00e7\u00e3o de 3,5 metros de pl\u00e1stico por minuto<\/strong>. Para al\u00e9m disso, o volume e a temperatura podem ser facilmente ajustados para assegurar uma boa selagem dos sacos de ar.<\/p>\n<p>Esta m\u00e1quina de enchimento disp\u00f5e de 2 tipos de pel\u00edcula pl\u00e1stica compat\u00edvel: sacos de ar simples e sacos de almofada de ar.<\/p>\n<p>Por outro lado, a<strong> AIRmove2<\/strong> \u00e9 uma m\u00e1quina de enchimento <strong>polivalente<\/strong> que permite a produ\u00e7\u00e3o de<strong> sacos de ar, almofadas de ar e pel\u00edcula de bolha de ar<\/strong> de acordo com as suas necessidades. Utiliza\u00e7\u00e3o para pequenas e m\u00e9dias cad\u00eancias. Pode produzir cerca de <strong>200 a 500 pacotes di\u00e1rios<\/strong>.<\/p>\n<p><strong>Protege, preenche, separa, fixa e envolve os seus produtos dentro da embalagem, assegurando assim a boa qualidade do envio.<\/strong><\/p>\n<p>Para al\u00e9m disso, este modelo \u00e9 <strong>mais r\u00e1pido<\/strong>, o seu sistema produz <strong>10m de enchimento de pl\u00e1stico por minuto<\/strong>.<\/p>\n<p>Destacamos tamb\u00e9m a sua compacidade e leveza, bem como o facto de ser uma m\u00e1quina silenciosa e vers\u00e1til que pode ser utilizada como m\u00e1quina de mesa ou montado na parede.<\/p>\n<p>Por \u00faltimo, o AIRmove 2 \u00e9 de f\u00e1cil utiliza\u00e7\u00e3o e r\u00e1pido, arrancando com o painel de controlo digital. Apresenta 3 tipos de enchimento de ar compat\u00edvel: sacos de ar simples, almofadas com c\u00e2mara de ar e sacos bolha.<\/p>\n<p>&nbsp;<\/p>\n<h3>Especifica\u00e7\u00f5es<\/h3>\n<p>Para a m\u00e1quina <strong>AIRmove<\/strong> existem 2 tipos de pel\u00edculas compat\u00edveis:<\/p>\n<ul>\n<li><strong>Sacos de ar simples<\/strong> (20cm de largura)<\/li>\n<li><strong>Sacos de almofada de ar<\/strong> com 16 c\u00e2maras (40 cm de largura). As pel\u00edculas s\u00e3o produzidas com polietileno e apresentadas em bobinas pr\u00e9-cortadas de 250m de comprimento.<\/li>\n<\/ul>\n<p>Por outro lado, a <strong>AIRmove2<\/strong> permite-lhe uma produ\u00e7\u00e3o r\u00e1pida e diretamente no ponto de embalagem. Assim, \u00e9 f\u00e1cil de integrar nos processos de embalagem existentes. O tipo de pel\u00edcula e o volume de enchimento s\u00e3o facilmente ajust\u00e1veis e a sua orienta\u00e7\u00e3o \u00e9 silenciosa. A sa\u00edda da pel\u00edcula \u00e9 reprogram\u00e1vel e facilmente controlada por pedal (dispon\u00edvel como acess\u00f3rio).<\/p>\n<p>Por \u00faltimo, a <strong>Airmove 2<\/strong> apresenta 3 tipos compat\u00edveis de enchimento de ar produzidos em rolos de polietileno pr\u00e9-cortados. S\u00e3o apresentados em bobinas pr\u00e9-cortadas de 350m de comprimento:<\/p>\n<ul>\n<li><strong>Sacos de ar simples<\/strong> para enchimento e fixa\u00e7\u00e3o no interior das caixas.<\/li>\n<li><strong>Almofada de ar<\/strong> ou saco duplo: para embalar e separar produtos.<\/li>\n<li><strong>Pel\u00edcula bolha para embalar<\/strong>, separar e preencher caixas.<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;4.24.0&#8243; custom_padding=&#8221;|||80px|false|false&#8221; custom_padding_tablet=&#8221;|||80px|false|false&#8221; custom_padding_phone=&#8221;|||0px|false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/sercalia.com\/wp-content\/uploads\/2021\/07\/sercalia_airmove.jpg&#8221; alt=&#8221;AIRmove. Sistema de enchimento de embalagem. Sercalia&#8221; title_text=&#8221;AIRmove. Sistema de enchimento de embalagem. Sercalia&#8221; url=&#8221;https:\/\/conservatis.com\/es\/aplicaciones\/maquina-airmove&#8221; url_new_window=&#8221;on&#8221; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.17.6&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;500ms&#8221; animation_intensity_slide=&#8221;10%&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; animation=&#8221;left&#8221; sticky=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_image src=&#8221;https:\/\/sercalia.com\/wp-content\/uploads\/2021\/10\/sercalia_solicte_orcamento.jpg&#8221; alt=&#8221;Sistemas de enchimento de bolhas em caixas. Prote\u00e7\u00e3o. Solicite um or\u00e7amento, Sercalia&#8221; title_text=&#8221;Sistemas de enchimento de bolhas em caixas. Prote\u00e7\u00e3o. Solicite um or\u00e7amento, Sercalia&#8221; url=&#8221;#orcamento&#8221; url_new_window=&#8221;on&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.25.2&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_image src=&#8221;https:\/\/sercalia.com\/wp-content\/uploads\/2023\/10\/loja_online_conservatis-copia-2.webp&#8221; alt=&#8221;Loja online. Sercalia&#8221; title_text=&#8221;Ci&#8221; url=&#8221;https:\/\/conservatis.com\/pt\/sistemas-de-embalagem&#8221; url_new_window=&#8221;on&#8221; _builder_version=&#8221;4.24.0&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_image src=&#8221;https:\/\/sercalia.com\/wp-content\/uploads\/2021\/07\/sercalia_sistema_relleno_con_burbujas.jpg&#8221; alt=&#8221;Sistemas de enchimento de bolhas Sercalia&#8221; title_text=&#8221;sercalia_sistema_enchimento_de_bolhas&#8221; url=&#8221;https:\/\/conservatis.com\/es\/aplicaciones\/bobinas-para-maquina-airmove&#8221; url_new_window=&#8221;on&#8221; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;500ms&#8221; animation_intensity_slide=&#8221;10%&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; animation=&#8221;left&#8221; sticky=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_image src=&#8221;https:\/\/sercalia.com\/wp-content\/uploads\/2021\/07\/sercalia_airmove2.jpg&#8221; alt=&#8221;Machina de enchimento. AIRmove 2. Sistema de enchimento com ar. Sercalia&#8221; title_text=&#8221;Machina de enchimento. AIRmove 2. Sistema de enchimento com Ar. Sercalia&#8221; url=&#8221;https:\/\/conservatis.com\/es\/aplicaciones\/maquina-airmove-2&#8243; url_new_window=&#8221;on&#8221; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.17.6&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;500ms&#8221; animation_intensity_slide=&#8221;10%&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; animation=&#8221;left&#8221; sticky=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_image src=&#8221;https:\/\/sercalia.com\/wp-content\/uploads\/2021\/07\/sercalia_airmove2_relleno_burbujas.jpg&#8221; alt=&#8221;AIRmove. Machina de enchimento. Sistema embalagem. Bolhas de ar para embalar.Sercalia, &#8221; title_text=&#8221;AIRmove. Machina de enchimento. Sistema embalagem. Bolhas de ar para embalar.Sercalia, &#8221; url=&#8221;https:\/\/conservatis.com\/es\/aplicaciones\/maquina-airmove-2&#8243; url_new_window=&#8221;on&#8221; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.17.6&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;500ms&#8221; animation_intensity_slide=&#8221;10%&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; animation=&#8221;left&#8221; sticky=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_image src=&#8221;https:\/\/sercalia.com\/wp-content\/uploads\/2021\/07\/airmove_sercalia_modelos_films.jpg&#8221; alt=&#8221;AIRmove.Machina enchimento. Modelos Pel\u00edcula. Sercalia&#8221; title_text=&#8221; Sistema de enchimento de bolhas. airmove. Modelos Pel\u00edcula. Sercalia&#8221; url=&#8221;https:\/\/conservatis.com\/es\/aplicaciones\/bobinas-para-maquina-airmove-2&#8243; url_new_window=&#8221;on&#8221; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.17.6&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;500ms&#8221; animation_intensity_slide=&#8221;10%&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; animation=&#8221;left&#8221; sticky=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.23.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Fornecimento<\/h3>\n<p>Os equipamentos do sistema de enchimento de embalagens Airmove est\u00e3o dispon\u00edveis em 2 modelos:<\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.23.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div>\n<table style=\"border-bottom color: #d0dbe7; border-style: hidden;\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"border-bottom color: #d0dbe7; border-style: solid;\">\n<td style=\"width: 115.238px;\"><strong>Modelo<\/strong><\/td>\n<td style=\"width: 144.3px;\"><strong>Medidas<\/strong><\/td>\n<td style=\"height: 44px; width: 84.1625px;\"><strong>Peso<\/strong><\/td>\n<td style=\"height: 44px; width: 119.275px;\"><strong>Alimenta\u00e7\u00e3o<\/strong><\/td>\n<\/tr>\n<tr style=\"border-bottom color: #d0dbe7; border-style: solid;\">\n<td style=\"width: 115.238px;\">Airmove<\/td>\n<td style=\"height: 44px; width: 144.3px;\">largura 46 x altura 20 x fundo 22 cm<\/td>\n<td style=\"height: 44px; width: 84.1625px;\">3,30 Kg<\/td>\n<td style=\"height: 44px; width: 119.275px;\">220 V<\/td>\n<\/tr>\n<tr style=\"border-bottom color: #d0dbe7; border-style: solid;\">\n<td style=\"width: 115.238px;\">Airmove2<\/td>\n<td style=\"height: 44px; width: 144.3px;\">lagura 36,4 x altura 32,9 x fundo 37 cm<\/td>\n<td style=\"height: 44px; width: 84.1625px;\">6,5 kg<\/td>\n<td style=\"height: 44px; width: 119.275px;\">220 V<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/sercalia.com\/wp-content\/uploads\/2024\/01\/sistemas-de-enchimento-de-bolhas-em-caixas_sercalia.jpg&#8221; alt=&#8221;Airmove 2. Bobinas de bolsas_sercalia&#8221; title_text=&#8221;suministro sistemas de relleno&#8221; url=&#8221;https:\/\/conservatis.com\/es\/aplicaciones\/bobinas-para-maquina-airmove-2&#8243; url_new_window=&#8221;on&#8221; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.23.4&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;500ms&#8221; animation_intensity_slide=&#8221;10%&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; animation=&#8221;left&#8221; sticky=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.23.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div>\n<p>As respetivas bobinas est\u00e3o dispon\u00edveis em::<\/p>\n<\/div>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.23.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div>\n<table style=\"border-bottom color: #d0dbe7; border-style: hidden;\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"border-bottom color: #d0dbe7; border-style: solid;\">\n<td style=\"width: 111px; height: 47px;\"><strong>Modelo<\/strong><\/td>\n<td style=\"width: 138px; height: 47px;\"><strong>Tipo<\/strong><\/td>\n<td style=\"height: 47px; width: 81px;\"><strong>Comprimento da bobina<\/strong><\/td>\n<td style=\"height: 47px; width: 115px;\"><strong>Largura<\/strong><\/td>\n<td style=\"width: 113px; height: 47px;\"><strong>Comprimento pr\u00e9-cortado<\/strong><\/td>\n<\/tr>\n<tr style=\"border-bottom color: #d0dbe7; border-style: solid;\">\n<td style=\"width: 111px; height: 47px;\">Airmove<\/td>\n<td style=\"height: 47px; width: 138px;\">Saco simples<\/td>\n<td style=\"height: 47px; width: 81px;\">250 m<\/td>\n<td style=\"height: 47px; width: 115px;\">200 mm<\/td>\n<td style=\"width: 113px; height: 47px;\">120 mm<\/td>\n<\/tr>\n<tr style=\"border-bottom color: #d0dbe7; border-style: solid;\">\n<td style=\"width: 111px; height: 47px;\">Airmove<\/td>\n<td style=\"height: 47px; width: 138px;\">Saco de almofada<\/td>\n<td style=\"height: 47px; width: 81px;\">250 m<\/td>\n<td style=\"height: 47px; width: 115px;\">400 mm<\/td>\n<td style=\"width: 113px; height: 47px;\">250 mm<\/td>\n<\/tr>\n<tr style=\"border-bottom color: #d0dbe7; border-style: solid;\">\n<td style=\"width: 111px; height: 47px;\">Airmove2<\/td>\n<td style=\"height: 47px; width: 138px;\">Saco simples<\/td>\n<td style=\"height: 47px; width: 81px;\">350 m<\/td>\n<td style=\"height: 47px; width: 115px;\">200 mm<\/td>\n<td style=\"width: 113px; height: 47px;\">120 mm<\/td>\n<\/tr>\n<tr style=\"border-bottom color: #d0dbe7; border-style: solid;\">\n<td style=\"width: 111px; height: 47px;\">Airmove2<\/td>\n<td style=\"height: 47px; width: 138px;\">Saco de almofada de ar<\/td>\n<td style=\"height: 47px; width: 81px;\">350 m<\/td>\n<td style=\"height: 47px; width: 115px;\">400 mm<\/td>\n<td style=\"width: 113px; height: 47px;\">250 mm<\/td>\n<\/tr>\n<tr style=\"border-bottom color: #d0dbe7; border-style: solid;\">\n<td style=\"width: 111px; height: 47px;\">Airmove2<\/td>\n<td style=\"height: 47px; width: 138px;\">Bolhas<\/td>\n<td style=\"height: 47px; width: 81px;\">350 m<\/td>\n<td style=\"height: 47px; width: 115px;\">400 mm<\/td>\n<td style=\"width: 113px; height: 47px;\">160 mm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<\/div>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/sercalia.com\/wp-content\/uploads\/2024\/01\/especificacoes-bobinas-airmove_sercalia.jpg&#8221; alt=&#8221;Airmove. Bobinas de bolsas_sercalia&#8221; title_text=&#8221;bobinas airmove&#8221; url=&#8221;https:\/\/conservatis.com\/es\/aplicaciones\/bobinas-para-maquina-airmove-2&#8243; url_new_window=&#8221;on&#8221; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.23.4&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;500ms&#8221; animation_intensity_slide=&#8221;10%&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; animation=&#8221;left&#8221; sticky=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.24.0&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div>\n<p>Para solicitar um or\u00e7amento que se adeque \u00e0s suas necessidades, <a href=\"https:\/\/sercalia.com\/pt\/contacto-2\/\"><strong>contacte-nos.<\/strong><\/a><\/p>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#d8d8d8&#8243; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;30px||30px||false|false&#8221; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;2_3,1_3&#8243; _builder_version=&#8221;4.21.0&#8243; background_image=&#8221;https:\/\/sercalia.com\/wp-content\/uploads\/2023\/08\/packaging-sercalia.png&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_horizontal_offset=&#8221;0%&#8221; background_vertical_offset=&#8221;0%&#8221; max_width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|||0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.21.0&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Tamb\u00e9m pode estar interessado&#8221; content_max_width=&#8221;100%&#8221; admin_label=&#8221;Blurb&#8221; _builder_version=&#8221;4.25.2&#8243; header_text_color=&#8221;gcid-db3b4ee3-e134-4c73-b6cc-52bd4e6aede2&#8243; header_font_size=&#8221;25px&#8221; header_line_height=&#8221;1.2em&#8221; body_font=&#8221;Raleway||||||||&#8221; body_text_color=&#8221;gcid-db3b4ee3-e134-4c73-b6cc-52bd4e6aede2&#8243; body_font_size=&#8221;17px&#8221; body_line_height=&#8221;1.8em&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;|||80px|false|false&#8221; custom_margin_tablet=&#8221;|||170px|false|false&#8221; custom_margin_phone=&#8221;40px|||0px|false|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; animation_style=&#8221;zoom&#8221; animation_direction=&#8221;left&#8221; animation_intensity_zoom=&#8221;4%&#8221; hover_enabled=&#8221;0&#8243; body_font_size_tablet=&#8221;17px&#8221; body_font_size_phone=&#8221;16px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{%22gcid-db3b4ee3-e134-4c73-b6cc-52bd4e6aede2%22:%91%22header_text_color%22,%22body_text_color%22%93}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Para outros produtos relacionados com <strong><a href=\"https:\/\/sercalia.com\/pt\/fixacao\/\">amarra\u00e7\u00e3o<\/a><\/strong> e <strong><a href=\"https:\/\/sercalia.com\/pt\/fixacao\/\">prote\u00e7\u00e3o,<\/a><\/strong> temos o seguinte: <a href=\"https:\/\/sercalia.com\/pt\/airbags-sacos-de-ar-para-transporte-de-mercadorias\/\">Airbags insufl\u00e1veis,<\/a> <a href=\"https:\/\/sercalia.com\/pt\/slip-sheet-pallet\/\">Slip Sheet Palets,<\/a> <a href=\"https:\/\/sercalia.com\/pt\/cantoneiras-de-protecao-para-embalagens-por-medida\/\">Cantoneiras de prote\u00e7\u00e3o,<\/a> <a href=\"https:\/\/sercalia.com\/pt\/papel-antiderrapante\/\">papel antiderrapante,<\/a> <a href=\"https:\/\/sercalia.com\/pt\/tapete-antiderrapante\/\">tapete antiderrapante,<\/a> <a href=\"https:\/\/sercalia.com\/pt\/separador-palets\/\">separador de paletes,<\/a> <a href=\"https:\/\/sercalia.com\/pt\/protecao-bobinas-e-cabos-propaflex\/\">prote\u00e7\u00e3o de bobinas e cabos PROPAFLEX,<\/a><a href=\"https:\/\/sercalia.com\/pt\/bottom-liners\/\"> round bottom liners,<\/a> <a href=\"https:\/\/sercalia.com\/pt\/sistemas-de-relleno-con-burbujas-en-cajas\/\">sistemas de enchimento para caixas.<\/a><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/sercalia.com\/wp-content\/uploads\/2024\/02\/compra_online_em_conservatis.gif&#8221; alt=&#8221;Compre online em Conservatis&#8221; title_text=&#8221;compra_online_em_conservatis&#8221; url=&#8221;https:\/\/conservatis.com\/pt\/protecao&#8221; url_new_window=&#8221;on&#8221; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;4%&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#858786&#8243; custom_padding=&#8221;30px||30px||false|false&#8221; global_module=&#8221;50480&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;2_3,1_3&#8243; _builder_version=&#8221;4.21.0&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; max_width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|||0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.21.0&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_code admin_label=&#8221;ancora&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<a name=\"presupuesto\"><\/a><!-- [et_pb_line_break_holder] --><a name=\"orcamento\"><\/a>[\/et_pb_code][et_pb_blurb title=&#8221;Solicite um or\u00e7amento&#8221; content_max_width=&#8221;100%&#8221; disabled_on=&#8221;on|on|off&#8221; admin_label=&#8221;Blurb&#8221; _builder_version=&#8221;4.24.0&#8243; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;25px&#8221; header_line_height=&#8221;1.2em&#8221; body_font=&#8221;Raleway||||||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;22px&#8221; body_line_height=&#8221;1.8em&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;-30px||||false|false&#8221; custom_margin_tablet=&#8221;|||170px|false|false&#8221; custom_margin_phone=&#8221;|||0px|false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_intensity_slide=&#8221;4%&#8221; body_font_size_tablet=&#8221;22px&#8221; body_font_size_phone=&#8221;16px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]Pedir informa\u00e7\u00f5es sobre os nossos produtos.[\/et_pb_blurb][et_pb_code disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-1091525\"><form id=\"wpforms-form-1091525\" class=\"wpforms-validate wpforms-form\" data-formid=\"1091525\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/pt\/wp-json\/wp\/v2\/pages\/30761\" data-token=\"142bf489a1187e6107a333149a58c67d\" data-token-time=\"1778691178\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-1091525-field_0-container\" class=\"wpforms-field wpforms-field-name wpforms-one-half wpforms-first wpforms-one-third\" data-field-id=\"0\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1091525-field_0\">Nome <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1091525-field_0\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][0]\" placeholder=\"Nome\" required><\/div><div id=\"wpforms-1091525-field_1-container\" class=\"wpforms-field wpforms-field-email wpforms-one-third\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1091525-field_1\">Correio electr\u00f3nico <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-1091525-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"Correio electr\u00f3nico\" spellcheck=\"false\" required><\/div><div id=\"wpforms-1091525-field_6-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third\" data-field-id=\"6\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1091525-field_6\">Nome da Empresa<\/label><input type=\"text\" id=\"wpforms-1091525-field_6\" class=\"wpforms-field-large\" name=\"wpforms[fields][6]\" placeholder=\"Nome da Empresa\" ><\/div><div id=\"wpforms-1091525-field_13-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-first\" data-field-id=\"13\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1091525-field_13\">Contato telef\u00f3nico <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1091525-field_13\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][13]\" placeholder=\"Contato telef\u00f3nico\" required><\/div><div id=\"wpforms-1091525-field_19-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third\" data-field-id=\"19\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1091525-field_19\">Pa\u00eds <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1091525-field_19\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][19]\" placeholder=\"Pa\u00eds\" required><\/div><div id=\"wpforms-1091525-field_17-container\" class=\"wpforms-field wpforms-field-textarea wpforms-one-third\" data-field-id=\"17\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1091525-field_17\">Mensagem <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-1091525-field_17\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][17]\" placeholder=\"Mensagem\" required><\/textarea><\/div><div id=\"wpforms-1091525-field_12-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-id=\"12\"><label class=\"wpforms-field-label wpforms-label-hide\">Acuerdo GDPR  <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-1091525-field_12\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-1091525-field_12_1\" name=\"wpforms[fields][12][]\" value=\"Li e aceito a &lt;a style=&quot;color: #1d334a;&quot; href=&quot;\/pt\/politica-de-privacidade-e-aviso-legal\/&quot; target=&quot;-blank&quot;&gt;  Pol\u00edtica de Privacidade e o Aviso Legal&lt;\/a&gt;\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1091525-field_12_1\">Li e aceito a <a style=\"color: #1d334a\" href=\"\/pt\/politica-de-privacidade-e-aviso-legal\/\" target=\"-blank\">  Pol\u00edtica de Privacidade e o Aviso Legal<\/a> <span class=\"wpforms-required-label\">*<\/span><\/label><\/li><\/ul><div class=\"wpforms-field-description\">* Campo de preenchimento obrigat\u00f3rio\r\n\r\n<\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-1091525-field-hp\" class=\"wpforms-field-label\">Message<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-1091525-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-invisible\" ><div class=\"g-recaptcha\" data-sitekey=\"6LexWgEVAAAAAJzoLDQM9-mu9MnEPHdMIwvciNjz\" data-size=\"invisible\"><\/div><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"1091525\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/sercalia.com\/pt\/wp-json\/wp\/v2\/pages\/30761\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-1091525\" class=\"wpforms-submit\" data-alt-text=\"Sending\u2026\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;CONTACTE-NOS&#8221; url=&#8221;https:\/\/sercalia.com\/pt\/contacto-2\/&#8221; alt=&#8221;Contactar-nos. Pe\u00e7a um or\u00e7amento agora.&#8221; title_tablet=&#8221;COMPRAR ONLINE NA CONSERVATIS&#8221; title_phone=&#8221;COMPRAR ONLINE NA CONSERVATIS&#8221; title_last_edited=&#8221;off|desktop&#8221; content_tablet=&#8221;<\/p>\n<p>Pedir informa\u00e7\u00f5es sobre os nossos produtos.<\/p>\n<p><strong><a   style=%22color: #354d68;%22 href=%22\/pt?page_id=24249%22><img class=%22wp-image-52473 alignleft size-full%22 src=%22https:\/\/sercalia.com\/wp-content\/uploads\/2023\/10\/ico-presupuesto.gif%22 alt=%22presupuesto%22 width=%2240%22 height=%2255%22 \/> Pe\u00e7a j\u00e1 o seu or\u00e7amento<\/a><\/strong><\/p>\n<p>&#8221; content_phone=&#8221;<\/p>\n<p>Pedir informa\u00e7\u00f5es sobre os nossos produtos.<\/p>\n<p><strong><a style=%22color: #354d68;%22 href=%22\/pt?page_id=24249%22><img class=%22wp-image-52473 alignleft size-full%22 src=%22https:\/\/sercalia.com\/wp-content\/uploads\/2023\/10\/ico-presupuesto.gif%22 alt=%22presupuesto%22 width=%2240%22 height=%2255%22 \/> Pe\u00e7a j\u00e1 o seu or\u00e7amento<\/a><\/strong><\/p>\n<p>&#8221; content_last_edited=&#8221;on|tablet&#8221; admin_label=&#8221;Blurb&#8221; _builder_version=&#8221;4.25.2&#8243; header_font=&#8221;|600|||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;22px&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;1.3em&#8221; background_color=&#8221;gcid-be32d608-26f6-4242-8631-15d29a247ee0&#8243; background_image=&#8221;https:\/\/sercalia.com\/wp-content\/uploads\/2023\/08\/contactanos_sercalia.jpg&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;bottom_right&#8221; background_horizontal_offset=&#8221;0%&#8221; custom_margin=&#8221;-90px|||0px|false|false&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;0px|||0px|false|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;30px|80px|30px|30px|false|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;10px||||false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; animation_style=&#8221;zoom&#8221; animation_direction=&#8221;left&#8221; animation_intensity_zoom=&#8221;4%&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;16px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{%22gcid-be32d608-26f6-4242-8631-15d29a247ee0%22:%91%22background_color%22%93}&#8221;]<\/p>\n<p>Distinguimo-nos pela nossa aten\u00e7\u00e3o, flexibilidade, rapidez e fiabilidade de entrega. O melhor servi\u00e7o personalizado com um fornecedor fi\u00e1vel para entregas regulares.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Produtos de Acondicionamento | Prote\u00e7\u00e3oM\u00e1quinas e bobinas de sacos de ar insufl\u00e1veis e bolhas AIRmove para prote\u00e7\u00e3o e envio de pequenas quantidades de embalagens.Descri\u00e7\u00e3o Os sistemas de enchimento de bolhas AIRmove em caixas s\u00e3o a solu\u00e7\u00e3o perfeita para a prote\u00e7\u00e3o com airbags ou sacos insufl\u00e1veis para envios pequenos e m\u00e9dios (30 a 500 envios di\u00e1rios). [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":29408,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-30761","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enchimento para caixas. Maquinas de enchimento - Sercalia<\/title>\n<meta name=\"description\" content=\"Sistemas de enchimento para caixas para prote\u00e7\u00e3o de envios de pequenas e m\u00e9dias embalagens. Maquina de enchimento. Airmove.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sercalia.com\/pt\/sistemas-de-relleno-con-burbujas-en-cajas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enchimento para caixas. Maquinas de enchimento - Sercalia\" \/>\n<meta property=\"og:description\" content=\"Sistemas de enchimento para caixas para prote\u00e7\u00e3o de envios de pequenas e m\u00e9dias embalagens. Maquina de enchimento. Airmove.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sercalia.com\/pt\/sistemas-de-relleno-con-burbujas-en-cajas\/\" \/>\n<meta property=\"og:site_name\" content=\"sercalia.com\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-07T14:29:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sercalia.com\/wp-content\/uploads\/2021\/07\/sercalia_airmove2_relleno_burbujas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"572\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sercalia.com\\\/pt\\\/sistemas-de-relleno-con-burbujas-en-cajas\\\/\",\"url\":\"https:\\\/\\\/sercalia.com\\\/pt\\\/sistemas-de-relleno-con-burbujas-en-cajas\\\/\",\"name\":\"Enchimento para caixas. Maquinas de enchimento - Sercalia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sercalia.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sercalia.com\\\/pt\\\/sistemas-de-relleno-con-burbujas-en-cajas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sercalia.com\\\/pt\\\/sistemas-de-relleno-con-burbujas-en-cajas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sercalia.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/sercalia_airmove2_relleno_burbujas.jpg\",\"datePublished\":\"2021-10-04T10:50:46+00:00\",\"dateModified\":\"2024-08-07T14:29:26+00:00\",\"description\":\"Sistemas de enchimento para caixas para prote\u00e7\u00e3o de envios de pequenas e m\u00e9dias embalagens. Maquina de enchimento. Airmove.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sercalia.com\\\/pt\\\/sistemas-de-relleno-con-burbujas-en-cajas\\\/#breadcrumb\"},\"inLanguage\":\"pt\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sercalia.com\\\/pt\\\/sistemas-de-relleno-con-burbujas-en-cajas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt\",\"@id\":\"https:\\\/\\\/sercalia.com\\\/pt\\\/sistemas-de-relleno-con-burbujas-en-cajas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sercalia.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/sercalia_airmove2_relleno_burbujas.jpg\",\"contentUrl\":\"https:\\\/\\\/sercalia.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/sercalia_airmove2_relleno_burbujas.jpg\",\"width\":600,\"height\":572,\"caption\":\"Syst\u00e8me de remplissage avec bulle pour les boites. Sercalia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sercalia.com\\\/pt\\\/sistemas-de-relleno-con-burbujas-en-cajas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sercalia.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enchimento para caixas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sercalia.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/sercalia.com\\\/pt\\\/\",\"name\":\"sercalia.com\",\"description\":\"Distribuci\u00f3n de absorbentes, productos qu\u00edmicos y packaging\",\"alternateName\":\"Sercalia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sercalia.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enchimento para caixas. Maquinas de enchimento - Sercalia","description":"Sistemas de enchimento para caixas para prote\u00e7\u00e3o de envios de pequenas e m\u00e9dias embalagens. Maquina de enchimento. Airmove.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sercalia.com\/pt\/sistemas-de-relleno-con-burbujas-en-cajas\/","og_locale":"pt_PT","og_type":"article","og_title":"Enchimento para caixas. Maquinas de enchimento - Sercalia","og_description":"Sistemas de enchimento para caixas para prote\u00e7\u00e3o de envios de pequenas e m\u00e9dias embalagens. Maquina de enchimento. Airmove.","og_url":"https:\/\/sercalia.com\/pt\/sistemas-de-relleno-con-burbujas-en-cajas\/","og_site_name":"sercalia.com","article_modified_time":"2024-08-07T14:29:26+00:00","og_image":[{"width":600,"height":572,"url":"https:\/\/sercalia.com\/wp-content\/uploads\/2021\/07\/sercalia_airmove2_relleno_burbujas.jpg","type":"image\/jpeg"}],"twitter_misc":{"Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sercalia.com\/pt\/sistemas-de-relleno-con-burbujas-en-cajas\/","url":"https:\/\/sercalia.com\/pt\/sistemas-de-relleno-con-burbujas-en-cajas\/","name":"Enchimento para caixas. Maquinas de enchimento - Sercalia","isPartOf":{"@id":"https:\/\/sercalia.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sercalia.com\/pt\/sistemas-de-relleno-con-burbujas-en-cajas\/#primaryimage"},"image":{"@id":"https:\/\/sercalia.com\/pt\/sistemas-de-relleno-con-burbujas-en-cajas\/#primaryimage"},"thumbnailUrl":"https:\/\/sercalia.com\/wp-content\/uploads\/2021\/07\/sercalia_airmove2_relleno_burbujas.jpg","datePublished":"2021-10-04T10:50:46+00:00","dateModified":"2024-08-07T14:29:26+00:00","description":"Sistemas de enchimento para caixas para prote\u00e7\u00e3o de envios de pequenas e m\u00e9dias embalagens. Maquina de enchimento. Airmove.","breadcrumb":{"@id":"https:\/\/sercalia.com\/pt\/sistemas-de-relleno-con-burbujas-en-cajas\/#breadcrumb"},"inLanguage":"pt","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sercalia.com\/pt\/sistemas-de-relleno-con-burbujas-en-cajas\/"]}]},{"@type":"ImageObject","inLanguage":"pt","@id":"https:\/\/sercalia.com\/pt\/sistemas-de-relleno-con-burbujas-en-cajas\/#primaryimage","url":"https:\/\/sercalia.com\/wp-content\/uploads\/2021\/07\/sercalia_airmove2_relleno_burbujas.jpg","contentUrl":"https:\/\/sercalia.com\/wp-content\/uploads\/2021\/07\/sercalia_airmove2_relleno_burbujas.jpg","width":600,"height":572,"caption":"Syst\u00e8me de remplissage avec bulle pour les boites. Sercalia"},{"@type":"BreadcrumbList","@id":"https:\/\/sercalia.com\/pt\/sistemas-de-relleno-con-burbujas-en-cajas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sercalia.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Enchimento para caixas"}]},{"@type":"WebSite","@id":"https:\/\/sercalia.com\/pt\/#website","url":"https:\/\/sercalia.com\/pt\/","name":"sercalia.com","description":"Distribuci\u00f3n de absorbentes, productos qu\u00edmicos y packaging","alternateName":"Sercalia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sercalia.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt"}]}},"_links":{"self":[{"href":"https:\/\/sercalia.com\/pt\/wp-json\/wp\/v2\/pages\/30761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sercalia.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sercalia.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sercalia.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sercalia.com\/pt\/wp-json\/wp\/v2\/comments?post=30761"}],"version-history":[{"count":38,"href":"https:\/\/sercalia.com\/pt\/wp-json\/wp\/v2\/pages\/30761\/revisions"}],"predecessor-version":[{"id":1101655,"href":"https:\/\/sercalia.com\/pt\/wp-json\/wp\/v2\/pages\/30761\/revisions\/1101655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sercalia.com\/pt\/wp-json\/wp\/v2\/media\/29408"}],"wp:attachment":[{"href":"https:\/\/sercalia.com\/pt\/wp-json\/wp\/v2\/media?parent=30761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}